{"id":26261,"date":"2021-04-27T15:59:00","date_gmt":"2021-04-27T19:59:00","guid":{"rendered":"https:\/\/www.cancerresearch.org\/blog\/abril-2021\/richardc"},"modified":"2022-10-14T18:09:30","modified_gmt":"2022-10-14T22:09:30","slug":"richardc","status":"publish","type":"post","link":"https:\/\/www.cancerresearch.org\/es\/blog\/richardc","title":{"rendered":"Richard Catlett&#8217;s Immunotherapy Story"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Kidney Cancer\u00a0| 2007<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Cuando entr\u00e9 para que el m\u00e9dico del estudio me diera los resultados, me entreg\u00f3 el informe y las dos primeras palabras fueron \u00abreducci\u00f3n dr\u00e1stica\u00bb. Fue todo lo que le\u00ed. Y luego comenc\u00e9 a llorar.<\/p><\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\">La historia de Richard<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Una ma\u00f1ana de abril de 2007, Richard Catlett, que entonces ten\u00eda 67 a\u00f1os, se levant\u00f3 temprano para cortar el c\u00e9sped. Mientras caminaba por el pasto, su pierna cedi\u00f3 y se cay\u00f3. Ese fue el comienzo de lo que se convertir\u00eda en una batalla de siete a\u00f1os contra el c\u00e1ncer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El c\u00e1ncer hab\u00eda empezado en el ri\u00f1\u00f3n y luego se disemin\u00f3 a los huesos. Los m\u00e9dicos lo trataron con cirug\u00eda, radioterapia y un tratamiento dirigido denominado sunitinib (Sutent\u00ae). Esos tratamientos funcionaron durante un tiempo, pero finalmente el c\u00e1ncer regres\u00f3 con mucha determinaci\u00f3n y se extendi\u00f3 a los pulmones, el h\u00edgado y los ganglios linf\u00e1ticos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En octubre de 2013, Richard se inscribi\u00f3 en un ensayo cl\u00ednico de una inmunoterapia llamada&nbsp;nivolumab dirigida al punto de control PD-1, en&nbsp;el Seattle Cancer Care Alliance&nbsp;en Washington. La respuesta al tratamiento fue asombrosa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un a\u00f1o despu\u00e9s casi todos sus tumores se redujeron a nada. Volvi\u00f3 a caminar y a hacer ejercicio, a cuida sus manzanos y a disfrutar de estar con su esposa y su perra Chloe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Richard falleci\u00f3 en septiembre de 2020 y lo sobreviven su esposa, Dianne, y su hermana, Sherri Lewis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Publicado inicialmente el 20 de enero de 2015.<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Preguntas y respuestas<\/h2>\n\n\n\n\n<p class=\"wp-block-paragraph\">Era el 17 de abril de 2007. El d\u00eda anterior hab\u00eda estado en el gimnasio, aqu\u00ed en nuestra peque\u00f1a ciudad de Sequim, Washington, y hab\u00eda terminado el entrenamiento que hac\u00eda regularmente. As\u00ed que ah\u00ed estaba yo, delgado, en forma y fuerte. A la ma\u00f1ana siguiente, me levant\u00e9 para cortar el c\u00e9sped a las 9 en punto y en la mitad del jard\u00edn mis piernas simplemente se desintegraron. Me ca\u00ed. Qued\u00e9 tendido en el suelo. Mi pierna apuntaba hacia el este y yo al oeste. \u00ab\u00bfQu\u00e9 diablos est\u00e1 pasando aqu\u00ed?\u00bb Obviamente, me dol\u00eda y no hab\u00eda nadie en casa. Vivimos en el campo, en un terreno de 1 hect\u00e1rea. Trat\u00e9 de arrastrarme hasta la camioneta para agarrar el tel\u00e9fono celular, pero no pude. Recuerdo estar tendido pensando que ese era el final.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Empec\u00e9 a gritar. Como por arte de magia, la cara de mi vecino apareci\u00f3 por encima de la cerca a unos 150 metros de distancia, y le grit\u00e9 que llamara al 911. Me trataron por una fractura de pierna. Un tramo de 5 cm del hueso grande de la pierna izquierda se hab\u00eda m\u00e1s o menos desintegrado. Nadie hablaba de c\u00e1ncer en ese momento, pero lo pens\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Iba a controlarme con el cirujano todas las semanas y me hicieron una radiograf\u00eda. Por alguna raz\u00f3n, el hueso no sanaba. Cinco semanas m\u00e1s tarde dijo: \u00abMejor hago una biopsia\u00bb. Fue entonces cuando encontraron el c\u00e1ncer. Me dijeron que ven\u00eda del ri\u00f1\u00f3n. Dos d\u00edas despu\u00e9s me hicieron una TAC que confirm\u00f3 que ten\u00eda un tumor de 10.6 cm en el ri\u00f1\u00f3n izquierdo, que hab\u00eda hecho met\u00e1stasis en la pierna.<\/p>\n\n\n\n\n\n<p class=\"wp-block-paragraph\">Comenc\u00e9 con Sutent unas seis semanas luego de que me fracturara la pierna, aproximadamente una semana despu\u00e9s del diagn\u00f3stico. Termin\u00e9 tomando ese medicamento durante 18 meses con fant\u00e1sticos resultados. El tama\u00f1o del tumor hep\u00e1tico se redujo dr\u00e1sticamente y me sent\u00eda mejor. Llegu\u00e9 al punto en que pod\u00eda moverme con un bast\u00f3n y un andador y no hab\u00eda ning\u00fan otro indicio de la enfermedad. Estaba en remisi\u00f3n completa. Eso fue a principios de 2009.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego, una exploraci\u00f3n por TAC de rutina revel\u00f3 que ten\u00eda un ganglio linf\u00e1tico en el pecho que se estaba agrandando. Me operaron para extirparlo y volv\u00ed a estar en remisi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aproximadamente un a\u00f1o despu\u00e9s me encontraron un tumor en el pulm\u00f3n. No quer\u00eda volver a operarme, y encontr\u00e9 en Internet un estudio del Johns Hopkins donde hab\u00edan usado Sutent junto con radioterapia localizada en dosis altas, y eso es lo que recib\u00ed para las met\u00e1stasis pulmonares. Esta radioterapia localizada funcion\u00f3 a la perfecci\u00f3n y volv\u00ed a entrar en remisi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Volvi\u00f3 con fuerza. Empec\u00e9 a sentirme terriblemente mal; ten\u00eda problemas para respirar, no me sent\u00eda bien. Y entonces me dijeron que ten\u00eda un tumor en la columna. Me imagin\u00e9 en una silla de ruedas y luego muerto. Fue ah\u00ed cuando empec\u00e9 a intentar seriamente entrar en el ensayo de nivolumab. Llam\u00e9 al m\u00e9dico y le dije que quer\u00eda participar en su ensayo cl\u00ednico. Me aceptaron y fijaron mi primera infusi\u00f3n para el 16 de octubre.<\/p>\n\n\n\n\n\n<p class=\"wp-block-paragraph\">Por la manera en que me sent\u00eda, parec\u00eda que la inmunoterapia hab\u00eda surtido efecto casi de inmediato. Nunca se sabe con certeza, pero sent\u00eda que estaban pasando cosas importantes en mi cuerpo y bastante r\u00e1pidamente. Ocho semanas m\u00e1s tarde, cuando fui a buscar los resultados, el m\u00e9dico del estudio me entreg\u00f3 el informe. Baj\u00e9 la vista y lo le\u00ed. Las dos primeras palabras eran \u00abconsiderable reducci\u00f3n\u00bb; hasta ah\u00ed le\u00ed y luego me largu\u00e9 a llorar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sigui\u00f3 dici\u00e9ndome que mi carga tumoral se hab\u00eda reducido en m\u00e1s del 50&nbsp;% en ocho semanas. Eso era pasar de estar casi muerto a sentirme bastante bien. El \u00faltimo viernes (en septiembre de 2014)&nbsp;tuve la sexta exploraci\u00f3n por TAC y la sexta resonancia magn\u00e9tica, y la tendencia se manten\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los m\u00e1s de 30 tumores del pulm\u00f3n hab\u00edan desaparecido. No pudieron encontrar los tumores \u00f3seos y no han podido encontrarlos en m\u00e1s de seis meses. La lesi\u00f3n hep\u00e1tica, que originalmente ten\u00eda 10.4 cm de longitud, ahora mide 2.5 x 1.5 cm. As\u00ed que ha disminuido dr\u00e1sticamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No solo es sorprendente, es una bendici\u00f3n.<\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Kidney Cancer\u00a0| 2007 Cuando entr\u00e9 para que el m\u00e9dico del estudio me diera los resultados, me entreg\u00f3 el informe y las dos primeras palabras fueron \u00abreducci\u00f3n dr\u00e1stica\u00bb. Fue todo lo que le\u00ed. [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":21831,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[678],"tags":[687,439],"resource_cancer_types":[],"resource_patient_age":[],"resource_cancer_stage":[],"resource_treatment_type":[],"resource_treatment_status":[],"class_list":["post-26261","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-patient-story-es","tag-kidney-cancer-es","tag-patient-stories-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Richard Catlett&#039;s Immunotherapy Story - Cancer Research Institute<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cancerresearch.org\/blog\/richardc\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Richard Catlett&#039;s Immunotherapy Story - Cancer Research Institute\" \/>\n<meta property=\"og:description\" content=\"Kidney Cancer\u00a0| 2007 Cuando entr\u00e9 para que el m\u00e9dico del estudio me diera los resultados, me entreg\u00f3 el informe y las dos primeras palabras fueron \u00abreducci\u00f3n dr\u00e1stica\u00bb. Fue todo lo que le\u00ed. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cancerresearch.org\/blog\/richardc\" \/>\n<meta property=\"og:site_name\" content=\"Cancer Research Institute\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-27T19:59:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-14T22:09:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cancerresearch.org\/wp-content\/uploads\/2022\/07\/richard-catlett_440x440-_1_.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"440\" \/>\n\t<meta property=\"og:image:height\" content=\"440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"CRI Staff\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"CRI Staff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cancerresearch.org\\\/blog\\\/richardc#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cancerresearch.org\\\/blog\\\/richardc\"},\"author\":{\"name\":\"CRI Staff\",\"@id\":\"https:\\\/\\\/www.cancerresearch.org\\\/#\\\/schema\\\/person\\\/680495be68bab0b66f6ed175092684d4\"},\"headline\":\"Richard Catlett&#8217;s Immunotherapy Story\",\"datePublished\":\"2021-04-27T19:59:00+00:00\",\"dateModified\":\"2022-10-14T22:09:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cancerresearch.org\\\/blog\\\/richardc\"},\"wordCount\":1013,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cancerresearch.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cancerresearch.org\\\/blog\\\/richardc#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cancerresearch.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/richard-catlett_440x440-_1_.jpg\",\"keywords\":[\"kidney cancer\",\"patient stories\"],\"articleSection\":[\"Patient Story\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cancerresearch.org\\\/blog\\\/richardc\",\"url\":\"https:\\\/\\\/www.cancerresearch.org\\\/blog\\\/richardc\",\"name\":\"Richard Catlett's Immunotherapy Story - Cancer Research Institute\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cancerresearch.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cancerresearch.org\\\/blog\\\/richardc#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cancerresearch.org\\\/blog\\\/richardc#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cancerresearch.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/richard-catlett_440x440-_1_.jpg\",\"datePublished\":\"2021-04-27T19:59:00+00:00\",\"dateModified\":\"2022-10-14T22:09:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cancerresearch.org\\\/blog\\\/richardc#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cancerresearch.org\\\/blog\\\/richardc\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cancerresearch.org\\\/blog\\\/richardc#primaryimage\",\"url\":\"https:\\\/\\\/www.cancerresearch.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/richard-catlett_440x440-_1_.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cancerresearch.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/richard-catlett_440x440-_1_.jpg\",\"width\":440,\"height\":440,\"caption\":\"Richard Catlett\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cancerresearch.org\\\/blog\\\/richardc#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cancerresearch.org\\\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Richard Catlett&#8217;s Immunotherapy Story\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cancerresearch.org\\\/#website\",\"url\":\"https:\\\/\\\/www.cancerresearch.org\\\/\",\"name\":\"Cancer Research Institute\",\"description\":\"For a World Immune to Cancer\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cancerresearch.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cancerresearch.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cancerresearch.org\\\/#organization\",\"name\":\"Cancer Research Institute\",\"url\":\"https:\\\/\\\/www.cancerresearch.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cancerresearch.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cancerresearch.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/logo-gradient.svg\",\"contentUrl\":\"https:\\\/\\\/www.cancerresearch.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/logo-gradient.svg\",\"width\":156,\"height\":53,\"caption\":\"Cancer Research Institute\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cancerresearch.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cancerresearch.org\\\/#\\\/schema\\\/person\\\/680495be68bab0b66f6ed175092684d4\",\"name\":\"CRI Staff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02f0ef777fed64d4eb97f93e70b904a9061fb107f8ea80db798cc9417248410f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02f0ef777fed64d4eb97f93e70b904a9061fb107f8ea80db798cc9417248410f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02f0ef777fed64d4eb97f93e70b904a9061fb107f8ea80db798cc9417248410f?s=96&d=mm&r=g\",\"caption\":\"CRI Staff\"},\"url\":\"https:\\\/\\\/www.cancerresearch.org\\\/es\\\/blog\\\/author\\\/cristaff\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Richard Catlett's Immunotherapy Story - Cancer Research Institute","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cancerresearch.org\/blog\/richardc","og_locale":"es_ES","og_type":"article","og_title":"Richard Catlett's Immunotherapy Story - Cancer Research Institute","og_description":"Kidney Cancer\u00a0| 2007 Cuando entr\u00e9 para que el m\u00e9dico del estudio me diera los resultados, me entreg\u00f3 el informe y las dos primeras palabras fueron \u00abreducci\u00f3n dr\u00e1stica\u00bb. Fue todo lo que le\u00ed. [&hellip;]","og_url":"https:\/\/www.cancerresearch.org\/blog\/richardc","og_site_name":"Cancer Research Institute","article_published_time":"2021-04-27T19:59:00+00:00","article_modified_time":"2022-10-14T22:09:30+00:00","og_image":[{"width":440,"height":440,"url":"https:\/\/www.cancerresearch.org\/wp-content\/uploads\/2022\/07\/richard-catlett_440x440-_1_.jpg","type":"image\/jpeg"}],"author":"CRI Staff","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"CRI Staff","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cancerresearch.org\/blog\/richardc#article","isPartOf":{"@id":"https:\/\/www.cancerresearch.org\/blog\/richardc"},"author":{"name":"CRI Staff","@id":"https:\/\/www.cancerresearch.org\/#\/schema\/person\/680495be68bab0b66f6ed175092684d4"},"headline":"Richard Catlett&#8217;s Immunotherapy Story","datePublished":"2021-04-27T19:59:00+00:00","dateModified":"2022-10-14T22:09:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cancerresearch.org\/blog\/richardc"},"wordCount":1013,"publisher":{"@id":"https:\/\/www.cancerresearch.org\/#organization"},"image":{"@id":"https:\/\/www.cancerresearch.org\/blog\/richardc#primaryimage"},"thumbnailUrl":"https:\/\/www.cancerresearch.org\/wp-content\/uploads\/2022\/07\/richard-catlett_440x440-_1_.jpg","keywords":["kidney cancer","patient stories"],"articleSection":["Patient Story"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.cancerresearch.org\/blog\/richardc","url":"https:\/\/www.cancerresearch.org\/blog\/richardc","name":"Richard Catlett's Immunotherapy Story - Cancer Research Institute","isPartOf":{"@id":"https:\/\/www.cancerresearch.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cancerresearch.org\/blog\/richardc#primaryimage"},"image":{"@id":"https:\/\/www.cancerresearch.org\/blog\/richardc#primaryimage"},"thumbnailUrl":"https:\/\/www.cancerresearch.org\/wp-content\/uploads\/2022\/07\/richard-catlett_440x440-_1_.jpg","datePublished":"2021-04-27T19:59:00+00:00","dateModified":"2022-10-14T22:09:30+00:00","breadcrumb":{"@id":"https:\/\/www.cancerresearch.org\/blog\/richardc#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cancerresearch.org\/blog\/richardc"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cancerresearch.org\/blog\/richardc#primaryimage","url":"https:\/\/www.cancerresearch.org\/wp-content\/uploads\/2022\/07\/richard-catlett_440x440-_1_.jpg","contentUrl":"https:\/\/www.cancerresearch.org\/wp-content\/uploads\/2022\/07\/richard-catlett_440x440-_1_.jpg","width":440,"height":440,"caption":"Richard Catlett"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cancerresearch.org\/blog\/richardc#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cancerresearch.org\/es"},{"@type":"ListItem","position":2,"name":"Richard Catlett&#8217;s Immunotherapy Story"}]},{"@type":"WebSite","@id":"https:\/\/www.cancerresearch.org\/#website","url":"https:\/\/www.cancerresearch.org\/","name":"Cancer Research Institute","description":"For a World Immune to Cancer","publisher":{"@id":"https:\/\/www.cancerresearch.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cancerresearch.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cancerresearch.org\/#organization","name":"Cancer Research Institute","url":"https:\/\/www.cancerresearch.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cancerresearch.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.cancerresearch.org\/wp-content\/uploads\/2025\/05\/logo-gradient.svg","contentUrl":"https:\/\/www.cancerresearch.org\/wp-content\/uploads\/2025\/05\/logo-gradient.svg","width":156,"height":53,"caption":"Cancer Research Institute"},"image":{"@id":"https:\/\/www.cancerresearch.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.cancerresearch.org\/#\/schema\/person\/680495be68bab0b66f6ed175092684d4","name":"CRI Staff","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/02f0ef777fed64d4eb97f93e70b904a9061fb107f8ea80db798cc9417248410f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/02f0ef777fed64d4eb97f93e70b904a9061fb107f8ea80db798cc9417248410f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/02f0ef777fed64d4eb97f93e70b904a9061fb107f8ea80db798cc9417248410f?s=96&d=mm&r=g","caption":"CRI Staff"},"url":"https:\/\/www.cancerresearch.org\/es\/blog\/author\/cristaff"}]}},"_links":{"self":[{"href":"https:\/\/www.cancerresearch.org\/es\/wp-json\/wp\/v2\/posts\/26261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cancerresearch.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cancerresearch.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cancerresearch.org\/es\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cancerresearch.org\/es\/wp-json\/wp\/v2\/comments?post=26261"}],"version-history":[{"count":0,"href":"https:\/\/www.cancerresearch.org\/es\/wp-json\/wp\/v2\/posts\/26261\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cancerresearch.org\/es\/wp-json\/wp\/v2\/media\/21831"}],"wp:attachment":[{"href":"https:\/\/www.cancerresearch.org\/es\/wp-json\/wp\/v2\/media?parent=26261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cancerresearch.org\/es\/wp-json\/wp\/v2\/categories?post=26261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cancerresearch.org\/es\/wp-json\/wp\/v2\/tags?post=26261"},{"taxonomy":"resource_cancer_types","embeddable":true,"href":"https:\/\/www.cancerresearch.org\/es\/wp-json\/wp\/v2\/resource_cancer_types?post=26261"},{"taxonomy":"resource_patient_age","embeddable":true,"href":"https:\/\/www.cancerresearch.org\/es\/wp-json\/wp\/v2\/resource_patient_age?post=26261"},{"taxonomy":"resource_cancer_stage","embeddable":true,"href":"https:\/\/www.cancerresearch.org\/es\/wp-json\/wp\/v2\/resource_cancer_stage?post=26261"},{"taxonomy":"resource_treatment_type","embeddable":true,"href":"https:\/\/www.cancerresearch.org\/es\/wp-json\/wp\/v2\/resource_treatment_type?post=26261"},{"taxonomy":"resource_treatment_status","embeddable":true,"href":"https:\/\/www.cancerresearch.org\/es\/wp-json\/wp\/v2\/resource_treatment_status?post=26261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}